{"id":6608,"date":"2024-06-07T21:52:39","date_gmt":"2024-06-07T19:52:39","guid":{"rendered":"https:\/\/sacrafestival.org\/alma-garcia\/"},"modified":"2025-03-24T16:43:18","modified_gmt":"2025-03-24T15:43:18","slug":"alma-garcia","status":"publish","type":"post","link":"https:\/\/sacrafestival.org\/es\/alma-garcia\/","title":{"rendered":"Alma Garc\u00eda"},"content":{"rendered":"<p>La actriz, dramaturga y licenciada en Filolog\u00eda Hisp\u00e1nica Alma Garc\u00eda, (Manises), siempre ha tenido una gran pasi\u00f3n por el teatro. Se apunt\u00f3 a actividades extraescolares de teatro y perteneci\u00f3 al grupo de teatro Quart de Poblet. Otra de sus pasiones fue la poes\u00eda. Fue a los 14 a\u00f1os cuando empez\u00f3 a desarrollar anorexia nerviosa y a los 17 a\u00f1os ingres\u00f3 en una cl\u00ednica de Barcelona durante un a\u00f1o y dos meses.<\/p>\n<p>Una vez abandon\u00f3 la cl\u00ednica, aunque continu\u00f3 su lucha contra los trastornos alimentarios, se licenci\u00f3 en Teor\u00eda y Pr\u00e1ctica del Arte Dram\u00e1tico en la Academia de Artes Esc\u00e9nicas TOTART de Valencia y continu\u00f3 su formaci\u00f3n como actriz en la escuela de interpretaci\u00f3n Work in Progress, dirigida por Dar\u00edo Focal, en Madrid. Fue mientras terminaba un m\u00e1ster cuando tuvo la oportunidad de escribir su primera obra de teatro Qu\u00e9 bueno que fuera tu tierra, Gald\u00f3s. Fue un encargo que le hizo, viendo su potencial, uno de sus maestros, Jos\u00e9 G\u00f3mez Friha, que ten\u00eda una compa\u00f1\u00eda de teatro en Venecia y deb\u00eda crear una obra para la Biblioteca Nacional. Y si hay una palabra que define a Alma es creadora, porque desde all\u00ed escribi\u00f3 las obras Non confeso (Festival Integraci\u00f3n das Artes da Coru\u00f1a), O retablo dos monstros (Fundaci\u00f3n Mir\u00f3, Mallorca) y \u00abContra Ana\u00bb (Lo contrario), que tambi\u00e9n cuenta la historia de todos aquellos compa\u00f1eros de prisi\u00f3n (y familiares) que padecieron esta enfermedad o vivieron esos meses. Alma Garc\u00eda tambi\u00e9n es licenciada en Filolog\u00eda Hisp\u00e1nica.<\/p>\n<p>En el cine protagoniz\u00f3 el cortometraje Una mira de Alberto Baldini, y tambi\u00e9n la vimos en los cortometrajes Doopled y Algo de malicia, as\u00ed como en la serie D\u00e9jate ver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actriz, dramaturga y licenciada en Filolog\u00eda Hisp\u00e1nica Alma Garc\u00eda, (Manises), siempre ha tenido una gran pasi\u00f3n por el teatro. Se apunt\u00f3 a actividades extraescolares de teatro y perteneci\u00f3 al grupo de teatro Quart de Poblet. Otra de sus pasiones fue la poes\u00eda. Fue a los 14 a\u00f1os cuando empez\u00f3 a desarrollar anorexia nerviosa y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[211],"tags":[],"class_list":["post-6608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artistas-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alma Garc\u00eda - Sacra Festival<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sacrafestival.org\/es\/alma-garcia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alma Garc\u00eda - Sacra Festival\" \/>\n<meta property=\"og:description\" content=\"La actriz, dramaturga y licenciada en Filolog\u00eda Hisp\u00e1nica Alma Garc\u00eda, (Manises), siempre ha tenido una gran pasi\u00f3n por el teatro. Se apunt\u00f3 a actividades extraescolares de teatro y perteneci\u00f3 al grupo de teatro Quart de Poblet. Otra de sus pasiones fue la poes\u00eda. Fue a los 14 a\u00f1os cuando empez\u00f3 a desarrollar anorexia nerviosa y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sacrafestival.org\/es\/alma-garcia\/\" \/>\n<meta property=\"og:site_name\" content=\"Sacra Festival\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-07T19:52:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T15:43:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sacrafestival.org\/wp-content\/uploads\/2025\/03\/alma-garcia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"573\" \/>\n\t<meta property=\"og:image:height\" content=\"407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agustin Sanoguera Gongora\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agustin Sanoguera Gongora\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/\"},\"author\":{\"name\":\"Agustin Sanoguera Gongora\",\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/en\\\/#\\\/schema\\\/person\\\/78be82691b29bd34186c0e943b641397\"},\"headline\":\"Alma Garc\u00eda\",\"datePublished\":\"2024-06-07T19:52:39+00:00\",\"dateModified\":\"2025-03-24T15:43:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/\"},\"wordCount\":310,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sacrafestival.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/alma-garcia-1.jpg\",\"articleSection\":[\"Artistas 2026\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/\",\"url\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/\",\"name\":\"Alma Garc\u00eda - Sacra Festival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sacrafestival.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/alma-garcia-1.jpg\",\"datePublished\":\"2024-06-07T19:52:39+00:00\",\"dateModified\":\"2025-03-24T15:43:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/en\\\/#\\\/schema\\\/person\\\/78be82691b29bd34186c0e943b641397\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sacrafestival.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/alma-garcia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sacrafestival.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/alma-garcia-1.jpg\",\"width\":573,\"height\":407,\"caption\":\"Alma Garc\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/alma-garcia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/sacra-festival\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alma Garc\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sacrafestival.org\\\/en\\\/\",\"name\":\"Sacra Festival\",\"description\":\"Artes, natureza e vi\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sacrafestival.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/en\\\/#\\\/schema\\\/person\\\/78be82691b29bd34186c0e943b641397\",\"name\":\"Agustin Sanoguera Gongora\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sacrafestival.org\\\/wp-content\\\/litespeed\\\/avatar\\\/4fbca4d1afda4ad5e2c5c9add26fd623.jpg?ver=1778174795\",\"url\":\"https:\\\/\\\/sacrafestival.org\\\/wp-content\\\/litespeed\\\/avatar\\\/4fbca4d1afda4ad5e2c5c9add26fd623.jpg?ver=1778174795\",\"contentUrl\":\"https:\\\/\\\/sacrafestival.org\\\/wp-content\\\/litespeed\\\/avatar\\\/4fbca4d1afda4ad5e2c5c9add26fd623.jpg?ver=1778174795\",\"caption\":\"Agustin Sanoguera Gongora\"},\"url\":\"https:\\\/\\\/sacrafestival.org\\\/es\\\/author\\\/agus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alma Garc\u00eda - Sacra Festival","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sacrafestival.org\/es\/alma-garcia\/","og_locale":"es_ES","og_type":"article","og_title":"Alma Garc\u00eda - Sacra Festival","og_description":"La actriz, dramaturga y licenciada en Filolog\u00eda Hisp\u00e1nica Alma Garc\u00eda, (Manises), siempre ha tenido una gran pasi\u00f3n por el teatro. Se apunt\u00f3 a actividades extraescolares de teatro y perteneci\u00f3 al grupo de teatro Quart de Poblet. Otra de sus pasiones fue la poes\u00eda. Fue a los 14 a\u00f1os cuando empez\u00f3 a desarrollar anorexia nerviosa y [&hellip;]","og_url":"https:\/\/sacrafestival.org\/es\/alma-garcia\/","og_site_name":"Sacra Festival","article_published_time":"2024-06-07T19:52:39+00:00","article_modified_time":"2025-03-24T15:43:18+00:00","og_image":[{"width":573,"height":407,"url":"https:\/\/sacrafestival.org\/wp-content\/uploads\/2025\/03\/alma-garcia-1.jpg","type":"image\/jpeg"}],"author":"Agustin Sanoguera Gongora","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Agustin Sanoguera Gongora","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/#article","isPartOf":{"@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/"},"author":{"name":"Agustin Sanoguera Gongora","@id":"https:\/\/sacrafestival.org\/en\/#\/schema\/person\/78be82691b29bd34186c0e943b641397"},"headline":"Alma Garc\u00eda","datePublished":"2024-06-07T19:52:39+00:00","dateModified":"2025-03-24T15:43:18+00:00","mainEntityOfPage":{"@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/"},"wordCount":310,"commentCount":0,"image":{"@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/#primaryimage"},"thumbnailUrl":"https:\/\/sacrafestival.org\/wp-content\/uploads\/2025\/03\/alma-garcia-1.jpg","articleSection":["Artistas 2026"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sacrafestival.org\/es\/alma-garcia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/","url":"https:\/\/sacrafestival.org\/es\/alma-garcia\/","name":"Alma Garc\u00eda - Sacra Festival","isPartOf":{"@id":"https:\/\/sacrafestival.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/#primaryimage"},"image":{"@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/#primaryimage"},"thumbnailUrl":"https:\/\/sacrafestival.org\/wp-content\/uploads\/2025\/03\/alma-garcia-1.jpg","datePublished":"2024-06-07T19:52:39+00:00","dateModified":"2025-03-24T15:43:18+00:00","author":{"@id":"https:\/\/sacrafestival.org\/en\/#\/schema\/person\/78be82691b29bd34186c0e943b641397"},"breadcrumb":{"@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sacrafestival.org\/es\/alma-garcia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/#primaryimage","url":"https:\/\/sacrafestival.org\/wp-content\/uploads\/2025\/03\/alma-garcia-1.jpg","contentUrl":"https:\/\/sacrafestival.org\/wp-content\/uploads\/2025\/03\/alma-garcia-1.jpg","width":573,"height":407,"caption":"Alma Garc\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/sacrafestival.org\/es\/alma-garcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sacrafestival.org\/es\/sacra-festival\/"},{"@type":"ListItem","position":2,"name":"Alma Garc\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/sacrafestival.org\/en\/#website","url":"https:\/\/sacrafestival.org\/en\/","name":"Sacra Festival","description":"Artes, natureza e vi\u00f1o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sacrafestival.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sacrafestival.org\/en\/#\/schema\/person\/78be82691b29bd34186c0e943b641397","name":"Agustin Sanoguera Gongora","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sacrafestival.org\/wp-content\/litespeed\/avatar\/4fbca4d1afda4ad5e2c5c9add26fd623.jpg?ver=1778174795","url":"https:\/\/sacrafestival.org\/wp-content\/litespeed\/avatar\/4fbca4d1afda4ad5e2c5c9add26fd623.jpg?ver=1778174795","contentUrl":"https:\/\/sacrafestival.org\/wp-content\/litespeed\/avatar\/4fbca4d1afda4ad5e2c5c9add26fd623.jpg?ver=1778174795","caption":"Agustin Sanoguera Gongora"},"url":"https:\/\/sacrafestival.org\/es\/author\/agus\/"}]}},"_links":{"self":[{"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/posts\/6608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/comments?post=6608"}],"version-history":[{"count":2,"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/posts\/6608\/revisions"}],"predecessor-version":[{"id":7185,"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/posts\/6608\/revisions\/7185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/media\/7092"}],"wp:attachment":[{"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/media?parent=6608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/categories?post=6608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sacrafestival.org\/es\/wp-json\/wp\/v2\/tags?post=6608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}